{"id":9568,"date":"2020-01-18T17:50:23","date_gmt":"2020-01-18T16:50:23","guid":{"rendered":"https:\/\/www.aimcinternational.org\/wp-content\/uploads\/MemberCard\/Colomba-Luca_001.jpg"},"modified":"2020-01-18T17:50:23","modified_gmt":"2020-01-18T16:50:23","slug":"colomba-luca_001","status":"inherit","type":"attachment","link":"https:\/\/www.aimcinternational.org\/it\/colomba-luca_001\/","title":{"rendered":"Colomba-Luca_001"},"author":1,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.aimcinternational.org\/wp-content\/uploads\/MemberCard\/Colomba-Luca_001-scaled.jpg'><img width=\"300\" height=\"224\" src=\"https:\/\/www.aimcinternational.org\/wp-content\/uploads\/MemberCard\/Colomba-Luca_001-300x224.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.aimcinternational.org\/wp-content\/uploads\/MemberCard\/Colomba-Luca_001-300x224.jpg 300w, https:\/\/www.aimcinternational.org\/wp-content\/uploads\/MemberCard\/Colomba-Luca_001-1024x764.jpg 1024w, https:\/\/www.aimcinternational.org\/wp-content\/uploads\/MemberCard\/Colomba-Luca_001-768x573.jpg 768w, https:\/\/www.aimcinternational.org\/wp-content\/uploads\/MemberCard\/Colomba-Luca_001-1536x1146.jpg 1536w, https:\/\/www.aimcinternational.org\/wp-content\/uploads\/MemberCard\/Colomba-Luca_001-2048x1528.jpg 2048w, https:\/\/www.aimcinternational.org\/wp-content\/uploads\/MemberCard\/Colomba-Luca_001-469x350.jpg 469w, https:\/\/www.aimcinternational.org\/wp-content\/uploads\/MemberCard\/Colomba-Luca_001-150x112.jpg 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p> <a class=\"continue-reading-link\" href=\"https:\/\/www.aimcinternational.org\/it\/colomba-luca_001\/\">Continue reading<\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1911,"file":"MemberCard\/Colomba-Luca_001-scaled.jpg","sizes":{"medium":{"file":"Colomba-Luca_001-300x224.jpg","width":300,"height":224,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aimcinternational.org\/wp-content\/uploads\/MemberCard\/Colomba-Luca_001-300x224.jpg"},"large":{"file":"Colomba-Luca_001-1024x764.jpg","width":1024,"height":764,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aimcinternational.org\/wp-content\/uploads\/MemberCard\/Colomba-Luca_001-1024x764.jpg"},"thumbnail":{"file":"Colomba-Luca_001-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aimcinternational.org\/wp-content\/uploads\/MemberCard\/Colomba-Luca_001-150x150.jpg"},"medium_large":{"file":"Colomba-Luca_001-768x573.jpg","width":768,"height":573,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aimcinternational.org\/wp-content\/uploads\/MemberCard\/Colomba-Luca_001-768x573.jpg"},"1536x1536":{"file":"Colomba-Luca_001-1536x1146.jpg","width":1536,"height":1146,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aimcinternational.org\/wp-content\/uploads\/MemberCard\/Colomba-Luca_001-1536x1146.jpg"},"2048x2048":{"file":"Colomba-Luca_001-2048x1528.jpg","width":2048,"height":1528,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aimcinternational.org\/wp-content\/uploads\/MemberCard\/Colomba-Luca_001-2048x1528.jpg"},"gg_gallery_thumbnail":{"file":"Colomba-Luca_001-450x250.jpg","width":450,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aimcinternational.org\/wp-content\/uploads\/MemberCard\/Colomba-Luca_001-450x250.jpg"},"custom":{"file":"Colomba-Luca_001-469x350.jpg","width":469,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aimcinternational.org\/wp-content\/uploads\/MemberCard\/Colomba-Luca_001-469x350.jpg"},"post-thumbnail":{"file":"Colomba-Luca_001-150x112.jpg","width":150,"height":112,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aimcinternational.org\/wp-content\/uploads\/MemberCard\/Colomba-Luca_001-150x112.jpg"},"header":{"file":"Colomba-Luca_001-1200x120.jpg","width":1200,"height":120,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aimcinternational.org\/wp-content\/uploads\/MemberCard\/Colomba-Luca_001-1200x120.jpg"},"slider":{"file":"Colomba-Luca_001-1200x500.jpg","width":1200,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aimcinternational.org\/wp-content\/uploads\/MemberCard\/Colomba-Luca_001-1200x500.jpg"},"parabola-columns":{"file":"Colomba-Luca_001-254x278.jpg","width":254,"height":278,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aimcinternational.org\/wp-content\/uploads\/MemberCard\/Colomba-Luca_001-254x278.jpg"},"sow-carousel-default":{"file":"Colomba-Luca_001-272x182.jpg","width":272,"height":182,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aimcinternational.org\/wp-content\/uploads\/MemberCard\/Colomba-Luca_001-272x182.jpg"},"full":{"file":"Colomba-Luca_001-scaled.jpg","width":2560,"height":1911,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aimcinternational.org\/wp-content\/uploads\/MemberCard\/Colomba-Luca_001-scaled.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]},"original_image":"Colomba-Luca_001.jpg"},"post":null,"source_url":"https:\/\/www.aimcinternational.org\/wp-content\/uploads\/MemberCard\/Colomba-Luca_001-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.aimcinternational.org\/it\/wp-json\/wp\/v2\/media\/9568"}],"collection":[{"href":"https:\/\/www.aimcinternational.org\/it\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.aimcinternational.org\/it\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.aimcinternational.org\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aimcinternational.org\/it\/wp-json\/wp\/v2\/comments?post=9568"}]}}